{"id":184,"date":"2024-03-11T18:52:30","date_gmt":"2024-03-11T17:52:30","guid":{"rendered":"https:\/\/www.apdigroup.com\/?page_id=184"},"modified":"2026-05-25T15:46:44","modified_gmt":"2026-05-25T13:46:44","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/apdigroup.com\/en\/aviso-legal\/","title":{"rendered":"Legal Notice"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"184\" class=\"elementor elementor-184\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19b3fef2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19b3fef2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f2232e\" data-id=\"f2232e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d35b32f\" data-id=\"d35b32f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9e91c2 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"c9e91c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/apdigroup.com\/en\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-left\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M134.059 296H436c6.627 0 12-5.373 12-12v-56c0-6.627-5.373-12-12-12H134.059v-46.059c0-21.382-25.851-32.09-40.971-16.971L7.029 239.029c-9.373 9.373-9.373 24.569 0 33.941l86.059 86.059c15.119 15.119 40.971 4.411 40.971-16.971V296z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">  Return<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1687e9ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1687e9ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d1d1678\" data-id=\"3d1d1678\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c7c859a elementor-widget elementor-widget-text-editor\" data-id=\"2c7c859a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>AGRUPACI\u00d3N DE PROFESIONALES PARA EL DESARROLLO INTERNACIONAL, S.L. se reserva el derecho de modificar cualquier tipo de informaci\u00f3n que pudiera aparecer en el sitio web, sin que exista obligaci\u00f3n de preavisar o poner en conocimiento de los usuarios dichas obligaciones, entendi\u00e9ndose como suficiente con la publicaci\u00f3n en el sitio web de AGRUPACI\u00d3N DE PROFESIONALES PARA EL DESARROLLO INTERNACIONAL, S.L..<\/p><p>En cumplimiento del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico, a continuaci\u00f3n se exponen los datos identificativos de la empresa propietaria del dominio www.apdigroup.com:<\/p><p><strong>1. Datos identificativos:<\/strong><\/p><p>\u2013 Nombre de dominio: www.apdigroup.com<br \/>\u2013 Denominaci\u00f3n social: AGRUPACI\u00d3N DE PROFESIONALES PARA EL DESARROLLO INTERNACIONAL, S.L.<br \/>\u2013 NIF: B92332857<br \/>\u2013 Domicilio social: C\/ C\u00e1rcel Baja, 19, 2\u00ba, &#8211; 18001 GRANADA (Granada).<br \/>\u2013 Tel\u00e9fono: 858706957<br \/>\u2013 E-mail: administracion@apdigroup.com<br \/><span style=\"font-size: 1rem;\">\u2013\u00a0<\/span><span style=\"font-size: 1rem;\">Datos registrales:<\/span><\/p><p><strong>2. Derechos de propiedad intelectual e industrial:<\/strong><\/p><p>El sitio web, incluyendo a t\u00edtulo enunciativo pero no limitativo su programaci\u00f3n, edici\u00f3n, compilaci\u00f3n y dem\u00e1s elementos necesarios para su funcionamiento, los dise\u00f1os, logotipos, texto y\/o gr\u00e1ficos, son propiedad del responsable o, si es el caso, dispone de licencia o autorizaci\u00f3n expresa por parte de los autores.<\/p><p>Todos los contenidos del sitio web se encuentran debidamente protegidos por la normativa de propiedad intelectual e industrial, as\u00ed como inscritos en los registros p\u00fablicos correspondientes. Independientemente de la finalidad para la que fueran destinados, la reproducci\u00f3n total o parcial, uso, explotaci\u00f3n, distribuci\u00f3n y comercializaci\u00f3n, requiere en todo caso de la autorizaci\u00f3n escrita previa por parte del responsable. Cualquier uso no autorizado previamente se considera un incumplimiento grave de los derechos de propiedad intelectual o industrial del autor. Los dise\u00f1os, logotipos, texto y\/o gr\u00e1ficos ajenos al responsable y que pudieran aparecer en el sitio web, pertenecen a sus respectivos propietarios, siendo ellos mismos responsables de cualquier posible controversia que pudiera suscitarse respecto a los mismos.<\/p><p>El responsable reconoce a favor de sus titulares los correspondientes derechos de propiedad intelectual e industrial, no implicando su sola menci\u00f3n o aparici\u00f3n en el sitio web la existencia de derechos o responsabilidad alguna sobre los mismos, como tampoco respaldo, patrocinio o recomendaci\u00f3n por parte del mismo.<\/p><p>Para realizar cualquier tipo de observaci\u00f3n respecto a posibles incumplimientos de los derechos de propiedad intelectual o industrial, as\u00ed como sobre cualquiera de los contenidos del sitio web, puede hacerlo a trav\u00e9s del correo electr\u00f3nico international@apdigroup.com o a la siguiente direcci\u00f3n postal: PLAZA ISABEL LA CAT\u00d3LICA, 1. 4\u00ba 4\u00aa, &#8211; 18009 GRANADA (Granada). E-mail: international@apdigroup.com.<\/p><p><strong>3. Navegaci\u00f3n, acceso y seguridad:<\/strong><\/p><p>El acceso, navegaci\u00f3n y utilizaci\u00f3n de esta p\u00e1gina web implica por tu parte la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de la presente Pol\u00edtica de Privacidad y Protecci\u00f3n de datos, teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. En este sentido, se entender\u00e1 por Usuario a la persona que acceda, navegue, utilice o participe en los servicios y actividades, gratuitas u onerosas, desarrolladas en el Sitio Web.<\/p><p>El acceso, navegaci\u00f3n y utilizaci\u00f3n de este Sitio web supone la aceptaci\u00f3n expresa y sin reservas de todas las advertencias legales, condiciones y t\u00e9rminos de uso contenidas en el presente Pol\u00edtica de Privacidad y Protecci\u00f3n de datos. AGRUPACI\u00d3N DE PROFESIONALES PARA EL DESARROLLO INTERNACIONAL, S.L. realiza los m\u00e1ximos esfuerzos para que la navegaci\u00f3n se realice en las mejores condiciones y evitar los perjuicios de cualquier tipo que pudiesen ocasionarse durante la misma. AGRUPACI\u00d3N DE PROFESIONALES PARA EL DESARROLLO INTERNACIONAL, S.L. no se responsabiliza ni garantiza que el acceso a este Sitio web sea ininterrumpido o que est\u00e9 libre de error. Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio web, est\u00e9 libre de error o cause un da\u00f1o. En ning\u00fan caso AGRUPACI\u00d3N DE PROFESIONALES PARA EL DESARROLLO INTERNACIONAL, S.L. ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso y el uso de la p\u00e1gina Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus, ni se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio web. Los servicios ofertados en este Sitio web s\u00f3lo pueden ser utilizados correctamente si se cumplen las especificaciones t\u00e9cnicas para las que ha sido dise\u00f1ado.<\/p><p>Queda prohibido el acceso a este Sitio Web por parte de menores de 14 a\u00f1os, salvo que cuenten con la autorizaci\u00f3n previa y expresa de sus padres, tutores o representantes legales, los cuales ser\u00e1n considerados como responsables de los actos que lleven a cabo los menores a su cargo, conforme a la normativa vigente. En todo caso, se presumir\u00e1 que el acceso realizado por un menor al Sitio Web se ha realizado con autorizaci\u00f3n previa y expresa de sus padres, tutores o representantes legales.<\/p><p><strong>4. Exenci\u00f3n de responsabilidades el responsable:<\/strong><\/p><p>Se exime de cualquier tipo de responsabilidad derivada de la informaci\u00f3n publicada en su sitio web siempre que esta informaci\u00f3n haya sido manipulada o introducida por un tercero ajeno al mismo. Pol\u00edtica de enlaces desde el sitio web, es posible que se redirija a contenidos de terceros sitios web. Dado que el responsable no puede controlar siempre los contenidos introducidos por los terceros en sus respectivos sitios web, no asume ning\u00fan tipo de responsabilidad respecto a dichos contenidos. En todo caso, proceder\u00e1 a la retirada inmediata de cualquier contenido que pudiera contravenir la legislaci\u00f3n nacional o internacional, la moral o el orden p\u00fablico, procediendo a la retirada inmediata de la redirecci\u00f3n a dicho sitio web, poniendo en conocimiento de las autoridades competentes el contenido en cuesti\u00f3n. El responsable no se hace responsable de la informaci\u00f3n y contenidos almacenados, a t\u00edtulo enunciativo, pero no limitativo, en foros, chats, generadores de blogs, comentarios, redes sociales o cualquier otro medio que permita a terceros publicar contenidos de forma independiente en la p\u00e1gina web del responsable. Sin embargo, y en cumplimiento de lo dispuesto en los art\u00edculos 11 y 16 de la LSSICE, se pone a disposici\u00f3n de todos los usuarios, autoridades y fuerzas de seguridad, colaborando de forma activa en la retirada o, en su caso, bloqueo de todos aquellos contenidos que puedan afectar o contravenir la legislaci\u00f3n nacional o internacional, los derechos de terceros o la moral y el orden p\u00fablico.<\/p><p>En caso de que el usuario considere que existe en el sitio web alg\u00fan contenido que pudiera ser susceptible de esta clasificaci\u00f3n, se ruega lo notifique de forma inmediata al administrador del sitio web. Este sitio web ha sido revisado y probado para que funcione correctamente. En principio, puede garantizarse el correcto funcionamiento los 365 d\u00edas del a\u00f1o, 24 horas al d\u00eda. Sin embargo, el responsable no descarta la posibilidad de que existan ciertos errores de programaci\u00f3n, o que acontezcan causas de fuerza mayor, cat\u00e1strofes naturales, huelgas o circunstancias semejantes que hagan imposible el acceso a la p\u00e1gina web.<\/p><p><strong>5. Condiciones adicionales:<\/strong><\/p><p>El usuario que introduce los datos, es el responsable \u00fanico y final de la veracidad de la informaci\u00f3n suministrada en el servicio y en las modificaciones de los mismos que pueda realizar hasta la finalizaci\u00f3n del mismo.<\/p><p><strong>6. Actualizaci\u00f3n y modificaci\u00f3n de la informaci\u00f3n:<\/strong><\/p><p>La informaci\u00f3n que aparece en este sitio web es la vigente en la fecha de su \u00faltima actualizaci\u00f3n. AGRUPACI\u00d3N DE PROFESIONALES PARA EL DESARROLLO INTERNACIONAL, S.L. se reserva el derecho a actualizar, modificar o eliminar la informaci\u00f3n de este sitio web, pudiendo limitar o no permitir el acceso al mismo. No se podr\u00e1 alterar, cambiar, modificar, o adaptar este sitio web. Sin embargo, AGRUPACI\u00d3N DE PROFESIONALES PARA EL DESARROLLO INTERNACIONAL, S.L. se reserva la facultad de efectuar, en cualquier momento, cuantos cambios y modificaciones estime convenientes, pudiendo hacer uso de tal facultad en cualquier momento y sin previo aviso.<\/p><p><strong>7. Ley aplicable y jurisdicci\u00f3n:<\/strong><\/p><p>Las presentes Condiciones se regir\u00e1n e interpretar\u00e1n de acuerdo con la legislaci\u00f3n com\u00fan espa\u00f1ola. Para cuantas cuestiones pudieran surgir sobre la interpretaci\u00f3n, cumplimiento, rescisi\u00f3n o resoluci\u00f3n de las Condiciones Generales, las Partes se someten a la jurisdicci\u00f3n y competencia de los Juzgados y Tribunales del domicilio social del Responsable del sitio web. No obstante, lo anterior, de conformidad con la legislaci\u00f3n espa\u00f1ola, para cuantas cuestiones pudieran surgir en relaci\u00f3n con estas Condiciones Generales ser\u00e1n competentes los juzgados y tribunales del domicilio que resulte de aplicaci\u00f3n, de conformidad con el art\u00edculo 52 de la Ley de Enjuiciamiento Civil o norma sustitutiva aplicable en cada momento.<\/p><p>Aviso legal redactado y suministrado por PROTECTION REPORT S, S.L, <a href=\"http:\/\/www.protectionreport.com\" target=\"_blank\" rel=\"noopener nofollow\">empresa de RGPD<\/a> qui\u00e9n se reserva las acciones legales que correspondan contra todo aquel que copie y utilice de forma ileg\u00edtima el contenido.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Volver AGRUPACI\u00d3N DE PROFESIONALES PARA EL DESARROLLO INTERNACIONAL, S.L. se reserva el derecho de modificar cualquier tipo de informaci\u00f3n que pudiera aparecer en el sitio web, sin que exista obligaci\u00f3n de preavisar o poner en conocimiento de los usuarios dichas obligaciones, entendi\u00e9ndose como suficiente con la publicaci\u00f3n en el sitio web de AGRUPACI\u00d3N DE PROFESIONALES [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-184","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/apdigroup.com\/en\/wp-json\/wp\/v2\/pages\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apdigroup.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apdigroup.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apdigroup.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/apdigroup.com\/en\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":7,"href":"https:\/\/apdigroup.com\/en\/wp-json\/wp\/v2\/pages\/184\/revisions"}],"predecessor-version":[{"id":3415,"href":"https:\/\/apdigroup.com\/en\/wp-json\/wp\/v2\/pages\/184\/revisions\/3415"}],"wp:attachment":[{"href":"https:\/\/apdigroup.com\/en\/wp-json\/wp\/v2\/media?parent=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}